{"id":3771,"date":"2019-03-29T11:23:46","date_gmt":"2019-03-29T04:23:46","guid":{"rendered":"https:\/\/www.nova-organic.com\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/"},"modified":"2019-03-29T11:23:46","modified_gmt":"2019-03-29T04:23:46","slug":"%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2","status":"publish","type":"post","link":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/","title":{"rendered":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e04"},"content":{"rendered":"<div class=\"row align-center\"  id=\"row-1455589453\">\n\n\t<div id=\"col-410582173\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1696919118\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"583\" src=\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-1.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-1.png 1271w, https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-1-700x400.png 700w, https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-1-768x439.png 768w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1696919118 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2835513759\" class=\"text\">\n\t\t\n<p>\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e13 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 29 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2562<\/p>\n\t\t\n<style>\n#text-2835513759 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1142330101\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1703658490\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"682\" src=\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-2-1196x800.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-2-1196x800.png 1196w, https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-2-598x400.png 598w, https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-2-768x514.png 768w, https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-2-1536x1028.png 1536w, https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-2.png 1750w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1703658490 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1750146461\" class=\"text\">\n\t\t\n<p>\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e13 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 19 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2562<\/p>\n\t\t\n<style>\n#text-1750146461 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2450,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-3771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e04 - nova-organic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e04 - nova-organic\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/\" \/>\n<meta property=\"og:site_name\" content=\"nova-organic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/donuttthailand\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-29T04:23:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1271\" \/>\n\t<meta property=\"og:image:height\" content=\"726\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nova\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"nova\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/\"},\"author\":{\"name\":\"nova\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/#\/schema\/person\/988bd85a82ab7635b8ba94b3cca3fcf3\"},\"headline\":\"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e04\",\"datePublished\":\"2019-03-29T04:23:46+00:00\",\"dateModified\":\"2019-03-29T04:23:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/\"},\"wordCount\":35,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-1.png\",\"articleSection\":[\"Events\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/\",\"url\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/\",\"name\":\"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e04 - nova-organic\",\"isPartOf\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-1.png\",\"datePublished\":\"2019-03-29T04:23:46+00:00\",\"dateModified\":\"2019-03-29T04:23:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/#primaryimage\",\"url\":\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-1.png\",\"contentUrl\":\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-1.png\",\"width\":1271,\"height\":726},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.nova-organic.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e04\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/#website\",\"url\":\"https:\/\/www.nova-organic.com\/en\/\",\"name\":\"nova-organic\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nova-organic.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/#organization\",\"name\":\"nova-organic\",\"url\":\"https:\/\/www.nova-organic.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/11\/logo-nova-450px_2.png\",\"contentUrl\":\"http:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/11\/logo-nova-450px_2.png\",\"width\":450,\"height\":168,\"caption\":\"nova-organic\"},\"image\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/donuttthailand\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/#\/schema\/person\/988bd85a82ab7635b8ba94b3cca3fcf3\",\"name\":\"nova\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/531557f081a12bcbe96d726763e9d867?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/531557f081a12bcbe96d726763e9d867?s=96&d=mm&r=g\",\"caption\":\"nova\"},\"sameAs\":[\"http:\/\/www.nova-organic.com\"],\"url\":\"https:\/\/www.nova-organic.com\/en\/author\/nova\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e04 - nova-organic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/","og_locale":"en_US","og_type":"article","og_title":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e04 - nova-organic","og_url":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/","og_site_name":"nova-organic","article_publisher":"https:\/\/www.facebook.com\/donuttthailand","article_published_time":"2019-03-29T04:23:46+00:00","og_image":[{"width":1271,"height":726,"url":"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-1.png","type":"image\/png"}],"author":"nova","twitter_card":"summary_large_image","twitter_misc":{"Written by":"nova","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/#article","isPartOf":{"@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/"},"author":{"name":"nova","@id":"https:\/\/www.nova-organic.com\/en\/#\/schema\/person\/988bd85a82ab7635b8ba94b3cca3fcf3"},"headline":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e04","datePublished":"2019-03-29T04:23:46+00:00","dateModified":"2019-03-29T04:23:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/"},"wordCount":35,"commentCount":0,"publisher":{"@id":"https:\/\/www.nova-organic.com\/en\/#organization"},"image":{"@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-1.png","articleSection":["Events"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/","url":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/","name":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e04 - nova-organic","isPartOf":{"@id":"https:\/\/www.nova-organic.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/#primaryimage"},"image":{"@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-1.png","datePublished":"2019-03-29T04:23:46+00:00","dateModified":"2019-03-29T04:23:46+00:00","breadcrumb":{"@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/#primaryimage","url":"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-1.png","contentUrl":"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/12\/20210818-140146-1.png","width":1271,"height":726},{"@type":"BreadcrumbList","@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%82%e0%b8%ad%e0%b8%87-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nova-organic.com\/en\/"},{"@type":"ListItem","position":2,"name":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e04"}]},{"@type":"WebSite","@id":"https:\/\/www.nova-organic.com\/en\/#website","url":"https:\/\/www.nova-organic.com\/en\/","name":"nova-organic","description":"","publisher":{"@id":"https:\/\/www.nova-organic.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nova-organic.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nova-organic.com\/en\/#organization","name":"nova-organic","url":"https:\/\/www.nova-organic.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nova-organic.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/11\/logo-nova-450px_2.png","contentUrl":"http:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/11\/logo-nova-450px_2.png","width":450,"height":168,"caption":"nova-organic"},"image":{"@id":"https:\/\/www.nova-organic.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/donuttthailand"]},{"@type":"Person","@id":"https:\/\/www.nova-organic.com\/en\/#\/schema\/person\/988bd85a82ab7635b8ba94b3cca3fcf3","name":"nova","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nova-organic.com\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/531557f081a12bcbe96d726763e9d867?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/531557f081a12bcbe96d726763e9d867?s=96&d=mm&r=g","caption":"nova"},"sameAs":["http:\/\/www.nova-organic.com"],"url":"https:\/\/www.nova-organic.com\/en\/author\/nova\/"}]}},"_links":{"self":[{"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/posts\/3771"}],"collection":[{"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/comments?post=3771"}],"version-history":[{"count":0,"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/posts\/3771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/media\/2450"}],"wp:attachment":[{"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/media?parent=3771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/categories?post=3771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/tags?post=3771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}