{"id":3784,"date":"2021-04-09T16:08:57","date_gmt":"2021-04-09T09:08:57","guid":{"rendered":""},"modified":"2024-02-19T13:51:42","modified_gmt":"2024-02-19T06:51:42","slug":"%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97","status":"publish","type":"post","link":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/","title":{"rendered":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e2b\u0e32\u0e22\u0e43\u0e08 (CPAP) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e23\u0e04\u0e17\u0e23\u0e27\u0e07\u0e2d\u0e01 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 1 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17"},"content":{"rendered":"<div class=\"row align-center\"  id=\"row-1250578148\">\n\n\t<div id=\"col-1926617810\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_739024668\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"991\" height=\"800\" src=\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-991x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-991x800.jpg 991w, https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-495x400.jpg 495w, https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-768x620.jpg 768w, https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-1536x1240.jpg 1536w, https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1.jpg 1578w\" sizes=\"(max-width: 991px) 100vw, 991px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_739024668 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"text-2502182085\" class=\"text\">\n\t\t\n<p>\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e2b\u0e32\u0e22\u0e43\u0e08 \u0e13 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 9 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2564<\/p>\n\t\t\n<style>\n#text-2502182085 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-3784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e2b\u0e32\u0e22\u0e43\u0e08 (CPAP) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e23\u0e04\u0e17\u0e23\u0e27\u0e07\u0e2d\u0e01 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 1 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 - nova-organic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e2b\u0e32\u0e22\u0e43\u0e08 (CPAP) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e23\u0e04\u0e17\u0e23\u0e27\u0e07\u0e2d\u0e01 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 1 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 - nova-organic\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/\" \/>\n<meta property=\"og:site_name\" content=\"nova-organic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/donuttthailand\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-09T09:08:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T06:51:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1578\" \/>\n\t<meta property=\"og:image:height\" content=\"1274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nova\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"nova\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/\"},\"author\":{\"name\":\"nova\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/#\/schema\/person\/988bd85a82ab7635b8ba94b3cca3fcf3\"},\"headline\":\"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e2b\u0e32\u0e22\u0e43\u0e08 (CPAP) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e23\u0e04\u0e17\u0e23\u0e27\u0e07\u0e2d\u0e01 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 1 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\",\"datePublished\":\"2021-04-09T09:08:57+00:00\",\"dateModified\":\"2024-02-19T06:51:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/\"},\"wordCount\":21,\"publisher\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-1.jpg\",\"articleSection\":[\"Events\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/\",\"url\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/\",\"name\":\"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e2b\u0e32\u0e22\u0e43\u0e08 (CPAP) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e23\u0e04\u0e17\u0e23\u0e27\u0e07\u0e2d\u0e01 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 1 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 - nova-organic\",\"isPartOf\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-1.jpg\",\"datePublished\":\"2021-04-09T09:08:57+00:00\",\"dateModified\":\"2024-02-19T06:51:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/#primaryimage\",\"url\":\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-1.jpg\",\"contentUrl\":\"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-1.jpg\",\"width\":1578,\"height\":1274},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.nova-organic.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e2b\u0e32\u0e22\u0e43\u0e08 (CPAP) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e23\u0e04\u0e17\u0e23\u0e27\u0e07\u0e2d\u0e01 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 1 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/#website\",\"url\":\"https:\/\/www.nova-organic.com\/en\/\",\"name\":\"nova-organic\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nova-organic.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/#organization\",\"name\":\"nova-organic\",\"url\":\"https:\/\/www.nova-organic.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/11\/logo-nova-450px_2.png\",\"contentUrl\":\"http:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/11\/logo-nova-450px_2.png\",\"width\":450,\"height\":168,\"caption\":\"nova-organic\"},\"image\":{\"@id\":\"https:\/\/www.nova-organic.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/donuttthailand\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/#\/schema\/person\/988bd85a82ab7635b8ba94b3cca3fcf3\",\"name\":\"nova\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.nova-organic.com\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/531557f081a12bcbe96d726763e9d867?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/531557f081a12bcbe96d726763e9d867?s=96&d=mm&r=g\",\"caption\":\"nova\"},\"sameAs\":[\"http:\/\/www.nova-organic.com\"],\"url\":\"https:\/\/www.nova-organic.com\/en\/author\/nova\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e2b\u0e32\u0e22\u0e43\u0e08 (CPAP) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e23\u0e04\u0e17\u0e23\u0e27\u0e07\u0e2d\u0e01 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 1 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 - nova-organic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/","og_locale":"en_US","og_type":"article","og_title":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e2b\u0e32\u0e22\u0e43\u0e08 (CPAP) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e23\u0e04\u0e17\u0e23\u0e27\u0e07\u0e2d\u0e01 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 1 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 - nova-organic","og_url":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/","og_site_name":"nova-organic","article_publisher":"https:\/\/www.facebook.com\/donuttthailand","article_published_time":"2021-04-09T09:08:57+00:00","article_modified_time":"2024-02-19T06:51:42+00:00","og_image":[{"width":1578,"height":1274,"url":"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-1.jpg","type":"image\/jpeg"}],"author":"nova","twitter_card":"summary_large_image","twitter_misc":{"Written by":"nova"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/#article","isPartOf":{"@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/"},"author":{"name":"nova","@id":"https:\/\/www.nova-organic.com\/en\/#\/schema\/person\/988bd85a82ab7635b8ba94b3cca3fcf3"},"headline":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e2b\u0e32\u0e22\u0e43\u0e08 (CPAP) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e23\u0e04\u0e17\u0e23\u0e27\u0e07\u0e2d\u0e01 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 1 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17","datePublished":"2021-04-09T09:08:57+00:00","dateModified":"2024-02-19T06:51:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/"},"wordCount":21,"publisher":{"@id":"https:\/\/www.nova-organic.com\/en\/#organization"},"image":{"@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-1.jpg","articleSection":["Events"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/","url":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/","name":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e2b\u0e32\u0e22\u0e43\u0e08 (CPAP) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e23\u0e04\u0e17\u0e23\u0e27\u0e07\u0e2d\u0e01 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 1 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 - nova-organic","isPartOf":{"@id":"https:\/\/www.nova-organic.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/#primaryimage"},"image":{"@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-1.jpg","datePublished":"2021-04-09T09:08:57+00:00","dateModified":"2024-02-19T06:51:42+00:00","breadcrumb":{"@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/#primaryimage","url":"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-1.jpg","contentUrl":"https:\/\/www.nova-organic.com\/wp-content\/uploads\/2020\/04\/20210818-141640-1-1.jpg","width":1578,"height":1274},{"@type":"BreadcrumbList","@id":"https:\/\/www.nova-organic.com\/en\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%8a%e0%b9%88%e0%b8%a7%e0%b8%a2%e0%b8%ab%e0%b8%b2%e0%b8%a2%e0%b9%83%e0%b8%88-cpap-%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%97%e0%b8%b2%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b9%81%e0%b8%81%e0%b9%88-%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b8%97%e0%b8%a3%e0%b8%a7%e0%b8%87%e0%b8%ad%e0%b8%81-%e0%b8%a1%e0%b8%b9%e0%b8%a5%e0%b8%84%e0%b9%88%e0%b8%b2-1-%e0%b8%a5%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%9a%e0%b8%b2%e0%b8%97\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nova-organic.com\/en\/"},{"@type":"ListItem","position":2,"name":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e2b\u0e32\u0e22\u0e43\u0e08 (CPAP) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e42\u0e23\u0e04\u0e17\u0e23\u0e27\u0e07\u0e2d\u0e01 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 1 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17"}]},{"@type":"WebSite","@id":"https:\/\/www.nova-organic.com\/en\/#website","url":"https:\/\/www.nova-organic.com\/en\/","name":"nova-organic","description":"","publisher":{"@id":"https:\/\/www.nova-organic.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nova-organic.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nova-organic.com\/en\/#organization","name":"nova-organic","url":"https:\/\/www.nova-organic.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nova-organic.com\/en\/#\/schema\/logo\/image\/","url":"http:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/11\/logo-nova-450px_2.png","contentUrl":"http:\/\/www.nova-organic.com\/wp-content\/uploads\/2023\/11\/logo-nova-450px_2.png","width":450,"height":168,"caption":"nova-organic"},"image":{"@id":"https:\/\/www.nova-organic.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/donuttthailand"]},{"@type":"Person","@id":"https:\/\/www.nova-organic.com\/en\/#\/schema\/person\/988bd85a82ab7635b8ba94b3cca3fcf3","name":"nova","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nova-organic.com\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/531557f081a12bcbe96d726763e9d867?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/531557f081a12bcbe96d726763e9d867?s=96&d=mm&r=g","caption":"nova"},"sameAs":["http:\/\/www.nova-organic.com"],"url":"https:\/\/www.nova-organic.com\/en\/author\/nova\/"}]}},"_links":{"self":[{"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/posts\/3784"}],"collection":[{"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/comments?post=3784"}],"version-history":[{"count":3,"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/posts\/3784\/revisions"}],"predecessor-version":[{"id":3787,"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/posts\/3784\/revisions\/3787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/media\/2461"}],"wp:attachment":[{"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/media?parent=3784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/categories?post=3784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nova-organic.com\/en\/wp-json\/wp\/v2\/tags?post=3784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}